{"id":2093,"date":"2017-01-16T08:26:33","date_gmt":"2017-01-16T07:26:33","guid":{"rendered":"http:\/\/www.apotecaverde.com\/blog\/?p=2093"},"modified":"2021-06-07T10:39:27","modified_gmt":"2021-06-07T08:39:27","slug":"por-que-aparece-el-dolor-y-como-tratarlo","status":"publish","type":"post","link":"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/","title":{"rendered":"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo!"},"content":{"rendered":"<p><a href=\"https:\/\/www.facebook.com\/FarmaciaGomezCassinello\" target=\"_blank\"><img class=\"aligncenter wp-image-2096 size-full\" src=\"http:\/\/www.apotecaverde.com\/blog\/wp-content\/uploads\/2016\/10\/dolor1.jpg\" alt=\"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo!\" height=\"auto\" srcset=\"https:\/\/www.apotecaverde.com\/blog\/wp-content\/uploads\/2016\/10\/dolor1.jpg 1200w, https:\/\/www.apotecaverde.com\/blog\/wp-content\/uploads\/2016\/10\/dolor1-300x213.jpg 300w, https:\/\/www.apotecaverde.com\/blog\/wp-content\/uploads\/2016\/10\/dolor1-211x150.jpg 211w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>Feliz y productivo d\u00eda! Hace poco lleg\u00f3 a nuestra Farmacia un chico joven, \u00a1\u00a1muy deportista, pero\u2026.hecho un cristo, le dol\u00eda todo!! Como yo digo en broma \u00a1\u00a1el deporte NO es salud!!!\u00a0 La verdad es que es raro el d\u00eda que alguien no llega a la farmacia pidi\u00e9ndonos algo para el dolor! \u00a1\u00a1El dolor es muy democr\u00e1tico!! Le da igual el sexo, la edad, la raza.. \u00a1es incre\u00edble! NO DISCRIMINA A NADIE!<\/p>\n<p>El <strong>dolor muscular<\/strong> se produce por una sobrecarga o lesi\u00f3n en el m\u00fasculo pues este debe de soportar mucho estr\u00e9s o tensi\u00f3n por un ejercicio deportivo intenso o por un trabajo f\u00edsico. Pueden estar involucrados ligamentos, tendones y los tejidos blandos que conectan los m\u00fasculos, huesos y \u00f3rganos, \u00a1\u00a1aqu\u00ed no se salva nadie, como ya hemos dicho, viva la democracia!!<\/p>\n<p>El dolor empieza justo cuando empezamos o terminamos de usar esta parte de nuestro cuerpo. Rara es la persona que no tiene pinchazos, dolor, rigidez o inflamaci\u00f3n en rodillas, mu\u00f1ecas, tobillos, codos\u2026etc, es un dolor muy limitante en el desarrollo de la vida diaria, ahora mismo estoy pensando en mi madre, \u00a1la pobre el abrir un bote le cuesta horrores! pues aparte algunas veces ese dolor trae consigo la p\u00e9rdida de fuerza.<\/p>\n<h4>Como curiosidad deciros que los especialistas dividen el dolor en dos tipos:<\/h4>\n<ul>\n<li><strong>Dolor de funci\u00f3n<\/strong>, este tipo de dolor es de caracter\u00edsticas mec\u00e1nicas, es decir,el dolor aumenta cuando hacemos movimientos y con los esfuerzos, en cambio no nos duele si est\u00e1 el miembro en reposo, son los t\u00edpicos de las artrosis, aqu\u00ed hay una destrucci\u00f3n del cart\u00edlago por desgaste<\/li>\n<\/ul>\n<ul>\n<li>Cuando el <strong>dolor es de caracter\u00edsticas inflamatorias<\/strong>, la zona no mejora \u00a1ni en reposo! Suele ir acompa\u00f1ado de enrojecimiento e inflamaci\u00f3n de la articulaci\u00f3n, es t\u00edpico de las artritis reumatoides, ya que \u00e9ste inflama la membrana sinovial de la articulaci\u00f3n.<\/li>\n<\/ul>\n<p>Lo m\u00e1s importante es fortalecer la musculatura que est\u00e1 alrededor, por lo que hacer ejercicio f\u00edsico todos los d\u00edas es bueno sobre todo para mejorar la movilidad articular y formar m\u00fasculo.<\/p>\n<p>\u00a1Si por casualidad llegamos a tener al dolor viviendo en el piso de al lado!, siempre podemos invitar a nuestras amigas las plantas para que les visiten. Quiero que todo el mundo tenga en cuenta que las plantas que usamos \u00a1NO son el t\u00edpico paracetamol o ibuprofeno que te lo tomas y se quita al ratillo el dolor! No funcionan as\u00ed y no quitan ese tipo de dolores agudos, \u00a1pero funcionan GENIAL para tratar el dolor a largo plazo! Me explico, las plantas necesitan su tiempo para que notemos sus efectos, necesitan unos d\u00edas para empezar a vislumbrar que funcionan&#8230; y creedme FUNCIONAN!!!<\/p>\n<h4>Adem\u00e1s estos peque\u00f1os consejitos naturales para aliviar el dolor:<\/h4>\n<ul>\n<li>Toma <a href=\"https:\/\/www.apotecaverde.com\/aceites-esenciales\/685-aceite-esencial-de-jengibre-de-pranarom-5ml-aceites-esenciales-pranarom.html\"><b>jengibre<\/b><\/a> a diario, este inhibe la liberaci\u00f3n de la sustancia P (es una sustancia que est\u00e1 muy relacionada con el dolor y la inflamaci\u00f3n), si puedes t\u00f3malo en extracto seco, pues va mucho m\u00e1s concentrado.<\/li>\n<\/ul>\n<ul>\n<li>Toma <a href=\" https:\/\/www.apotecaverde.com\/antioxidantes\/263-te-verde-sencha-mizuki-bio-de-alveus-50gr.html \"><b>t\u00e9 verde<\/b><\/a> de calidad a diario, es rico en catecolaminas que combaten los radicales libres que se producen en nuestro organismo, pudiendo producir inflamaciones y son tan perjudiciales para personas con artrosis y dolores articulares.<\/li>\n<\/ul>\n<ul>\n<li><b>la vitamina E <\/b>act\u00faa muy parecido a los antiinflamatorios de s\u00edntesis que conocemos (ibuprofeno, paracetamol\u2026), lo que hace es inhibir a las prostaglandinas, que son unas sustancias que producen nuestro cuerpo y se relacionan con la inflamaci\u00f3n y el dolor.<\/li>\n<\/ul>\n<ul>\n<li><b><b>elimina alimentos <\/b><\/b>como el <strong>trigo<\/strong> o <strong>cereales<\/strong> que contengan gluten de tu vida. Existen estudios cient\u00edficos que demuestran que estos alimentos producen inflamaci\u00f3n, si alguien tiene inter\u00e9s que se documente en disbiosis intestinal, \u00a1es alucinante!<\/li>\n<\/ul>\n<ul>\n<li><b><a href=\" https:\/\/www.apotecaverde.com\/medicina-natural\/613-dha-80-tg-npd1-de-laboratorio-egle-120-capsulas.html \"><b>\u00e1cidos grasos omega 3<\/b><\/a><\/b> como el DHA, EPA. En distintos estudios se ha visto que bloquean a los mediadores que producen inflamaci\u00f3n como son los eicosanoides y las citocinas proinflamatorias. Esto lo que produce en nuestro cuerpo es que NO se tenga que usar antiinflamatorios de s\u00edntesis, pero como ya os he comentado si te tomas una dosis de \u00e1cidos grasos omega 3, \u00a1te quitar\u00e1 el dolor cuando lleves un tiempo tom\u00e1ndolo!<\/li>\n<\/ul>\n<p>Bueno esto es todo por hoy, el pr\u00f3ximo d\u00eda os hablo de remedios para el dolor y la inflamaci\u00f3n con plantas medicinales, \u00a1\u00a1 ME ENCANTA PENSAR EN VERDE\u00a1\u00a1 \u00bfY a ti?<\/p>\n<p><strong>Referencias:<\/strong><\/p>\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Nieman%20DC%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24274358\">Nieman DC<\/a>, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Shanely%20RA%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24274358\">Shanely RA<\/a>, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Luo%20B%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=24274358\">Luo B<\/a>, <b>A commercialized dietary supplement alleviates joint pain in community adults: a double-blind, placebo-controlled community trial<\/b>. Nutr J. 2013 Nov 25;12(1):154. doi: 10.1186\/1475-2891-12-154.<\/p>\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Haghiac%20M%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=26340264\">Haghiac M<\/a>, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Yang%20XH%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=26340264\">Yang XH<\/a>, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Presley%20L%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=26340264\">Presley L<\/a><b> Dietary Omega-3 Fatty Acid Supplementation Reduces Inflammation in Obese Pregnant Women: A Randomized Double-Blind Controlled Clinical Trial<\/b>. PLoS One. 2015 Sep 4;10(9):e0137309. doi: 10.1371\/journal.pone.0137309. eCollection 2015<br \/>\n<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Lowe%20GM%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=26259232\">Lowe GM<\/a>, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Gana%20K%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=26259232\">Gana K<\/a>, <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/?term=Rahman%20K%5BAuthor%5D&amp;cauthor=true&amp;cauthor_uid=26259232\">Rahman K<\/a>. <b>Dietary supplementation with green tea extract promotes enhanced human leukocyte activity.<\/b> J Complement Integr Med. 2015 Dec;12(4):277-82. doi: 10.1515\/jcim-2014-0042.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feliz y productivo d\u00eda! Hace poco lleg\u00f3 a nuestra Farmacia un chico joven, \u00a1\u00a1muy deportista, pero\u2026.hecho un cristo, le dol\u00eda todo!! Como yo digo en broma \u00a1\u00a1el deporte NO es salud!!!\u00a0 La verdad es que es raro el d\u00eda que alguien no llega a la farmacia pidi\u00e9ndonos algo para el dolor! \u00a1\u00a1El dolor es muy<a class=\"read-more \" href=\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/\" title=\"Read More\"> <span class=\"button default\">Read More<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":2096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[10,7],"tags":[1490,1491,471,1484,1486,1485,1483,1354,1487,1482],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.5.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo! - Apoteca Verde<\/title>\n<meta name=\"description\" content=\"\u00c9stos son los 2 principales tipos de dolor y las razones de su aparici\u00f3n! 5 formas de combatir el dolor usando diferentes plantas y remedios naturales!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo! - Apoteca Verde\" \/>\n<meta property=\"og:description\" content=\"\u00c9stos son los 2 principales tipos de dolor y las razones de su aparici\u00f3n! 5 formas de combatir el dolor usando diferentes plantas y remedios naturales!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/\" \/>\n<meta property=\"og:site_name\" content=\"Apoteca Verde\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FarmaciaGomezCassinello\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-16T07:26:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-07T08:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.apotecaverde.com\/blog\/wp-content\/uploads\/2016\/10\/dolor1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Concha G\u00f3mez Cassinello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Concha G\u00f3mez Cassinello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/\",\"url\":\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/\",\"name\":\"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo! - Apoteca Verde\",\"isPartOf\":{\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/#website\"},\"datePublished\":\"2017-01-16T07:26:33+00:00\",\"dateModified\":\"2021-06-07T08:39:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/#\/schema\/person\/016bf376700fd60f52de6325bd183365\"},\"description\":\"\u00c9stos son los 2 principales tipos de dolor y las razones de su aparici\u00f3n! 5 formas de combatir el dolor usando diferentes plantas y remedios naturales!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.apotecaverde.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/#website\",\"url\":\"https:\/\/www.apotecaverde.com\/blog\/\",\"name\":\"Apoteca Verde\",\"description\":\"Blog sobre el uso de las plantas medicinales para cuidar la salud y bienestar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.apotecaverde.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/#\/schema\/person\/016bf376700fd60f52de6325bd183365\",\"name\":\"Concha G\u00f3mez Cassinello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.apotecaverde.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6165cee1ae46ac18cacb39f6d0f2b22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6165cee1ae46ac18cacb39f6d0f2b22?s=96&d=mm&r=g\",\"caption\":\"Concha G\u00f3mez Cassinello\"},\"description\":\"\u00a1Hola! soy Concha G\u00f3mez Cassinello, soy Granadina, pero Cordobesa de adopci\u00f3n; estudi\u00e9 Famacia en la Universidad de Granada; llevo m\u00e1s de 19 a\u00f1os siendo titular de Farmacia G\u00f3mez Cassinello y haciendo mil cosas, estoy en continua b\u00fasqueda y siento mucha curiosidad por todo. A raiz de nacer mi tercer hijo, me diagnosticaron un hipotiroidismo de Hashimoto, tras multiples visitas a diferentes endocrinos y que ninguno controlara mis s\u00edntomas y prescribirme m\u00faltiples f\u00e1rmacos, decid\u00ed ir a un nutricionista ortomolecular y ... \u00a1me cambi\u00f3 la vida! A ra\u00edz de esto me interes\u00e9 por todo lo natural, complementos nutricionales, cosmetica natural, alimentos, y decid\u00ed que la gente deb\u00eda conocer mejor todas aquellas cosas que tanto me hab\u00edan ayudado a m\u00ed. \u00a1BIENVENIDOS A BOTICA VERDE!, espero que os enamor\u00e9 tanto como a m\u00ed me entusiasma todo este mundo \u201cverde\u201d, \u00bfos apetece que empecemos?, podeis contactar conmigo a trav\u00e9s de info@boticaverde.es\",\"url\":\"https:\/\/www.apotecaverde.com\/blog\/author\/concha15\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo! - Apoteca Verde","description":"\u00c9stos son los 2 principales tipos de dolor y las razones de su aparici\u00f3n! 5 formas de combatir el dolor usando diferentes plantas y remedios naturales!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/","og_locale":"es_ES","og_type":"article","og_title":"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo! - Apoteca Verde","og_description":"\u00c9stos son los 2 principales tipos de dolor y las razones de su aparici\u00f3n! 5 formas de combatir el dolor usando diferentes plantas y remedios naturales!","og_url":"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/","og_site_name":"Apoteca Verde","article_publisher":"https:\/\/www.facebook.com\/FarmaciaGomezCassinello","article_published_time":"2017-01-16T07:26:33+00:00","article_modified_time":"2021-06-07T08:39:27+00:00","og_image":[{"width":1200,"height":850,"url":"https:\/\/www.apotecaverde.com\/blog\/wp-content\/uploads\/2016\/10\/dolor1.jpg","type":"image\/jpeg"}],"author":"Concha G\u00f3mez Cassinello","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Concha G\u00f3mez Cassinello","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/","url":"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/","name":"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo! - Apoteca Verde","isPartOf":{"@id":"https:\/\/www.apotecaverde.com\/blog\/#website"},"datePublished":"2017-01-16T07:26:33+00:00","dateModified":"2021-06-07T08:39:27+00:00","author":{"@id":"https:\/\/www.apotecaverde.com\/blog\/#\/schema\/person\/016bf376700fd60f52de6325bd183365"},"description":"\u00c9stos son los 2 principales tipos de dolor y las razones de su aparici\u00f3n! 5 formas de combatir el dolor usando diferentes plantas y remedios naturales!","breadcrumb":{"@id":"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.apotecaverde.com\/blog\/por-que-aparece-el-dolor-y-como-tratarlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.apotecaverde.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Por qu\u00e9 aparece el dolor y c\u00f3mo tratarlo!"}]},{"@type":"WebSite","@id":"https:\/\/www.apotecaverde.com\/blog\/#website","url":"https:\/\/www.apotecaverde.com\/blog\/","name":"Apoteca Verde","description":"Blog sobre el uso de las plantas medicinales para cuidar la salud y bienestar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.apotecaverde.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.apotecaverde.com\/blog\/#\/schema\/person\/016bf376700fd60f52de6325bd183365","name":"Concha G\u00f3mez Cassinello","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.apotecaverde.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6165cee1ae46ac18cacb39f6d0f2b22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6165cee1ae46ac18cacb39f6d0f2b22?s=96&d=mm&r=g","caption":"Concha G\u00f3mez Cassinello"},"description":"\u00a1Hola! soy Concha G\u00f3mez Cassinello, soy Granadina, pero Cordobesa de adopci\u00f3n; estudi\u00e9 Famacia en la Universidad de Granada; llevo m\u00e1s de 19 a\u00f1os siendo titular de Farmacia G\u00f3mez Cassinello y haciendo mil cosas, estoy en continua b\u00fasqueda y siento mucha curiosidad por todo. A raiz de nacer mi tercer hijo, me diagnosticaron un hipotiroidismo de Hashimoto, tras multiples visitas a diferentes endocrinos y que ninguno controlara mis s\u00edntomas y prescribirme m\u00faltiples f\u00e1rmacos, decid\u00ed ir a un nutricionista ortomolecular y ... \u00a1me cambi\u00f3 la vida! A ra\u00edz de esto me interes\u00e9 por todo lo natural, complementos nutricionales, cosmetica natural, alimentos, y decid\u00ed que la gente deb\u00eda conocer mejor todas aquellas cosas que tanto me hab\u00edan ayudado a m\u00ed. \u00a1BIENVENIDOS A BOTICA VERDE!, espero que os enamor\u00e9 tanto como a m\u00ed me entusiasma todo este mundo \u201cverde\u201d, \u00bfos apetece que empecemos?, podeis contactar conmigo a trav\u00e9s de info@boticaverde.es","url":"https:\/\/www.apotecaverde.com\/blog\/author\/concha15\/"}]}},"_links":{"self":[{"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/posts\/2093"}],"collection":[{"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/comments?post=2093"}],"version-history":[{"count":7,"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/posts\/2093\/revisions"}],"predecessor-version":[{"id":5473,"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/posts\/2093\/revisions\/5473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/media\/2096"}],"wp:attachment":[{"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/media?parent=2093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/categories?post=2093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.apotecaverde.com\/blog\/wp-json\/wp\/v2\/tags?post=2093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}